{"id":3,"count":7,"description":"","link":"http:\/\/btils.com\/outofoffice\/category\/travel\/","name":"Travel","slug":"travel","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/btils.com\/outofoffice\/wp-json\/wp\/v2\/categories\/3"}],"collection":[{"href":"http:\/\/btils.com\/outofoffice\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/btils.com\/outofoffice\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/btils.com\/outofoffice\/wp-json\/wp\/v2\/posts?categories=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}